{"id":1067979,"date":"2026-05-13T00:54:05","date_gmt":"2026-05-12T22:54:05","guid":{"rendered":"https:\/\/www.manzetticlothing.com\/prodotto\/senza-categoria\/caffenero-sandali-alcantara-en\/"},"modified":"2026-05-13T00:54:17","modified_gmt":"2026-05-12T22:54:17","slug":"caffenero-sandali-alcantara-en","status":"publish","type":"product","link":"https:\/\/www.manzetticlothing.com\/en\/product\/women\/shoes\/sandals\/caffenero-sandali-alcantara-en\/","title":{"rendered":"Prodotto"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":1067965,"template":"","meta":{"_acf_changed":false},"product_cat":[8240,8896,8236,9138,9128,8234],"product_tag":[],"giftcard-category":[],"class_list":{"0":"post-1067979","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-brands-women","7":"product_cat-caffenero-brands-women","8":"product_cat-new-arrivals","9":"product_cat-sandals","10":"product_cat-shoes","11":"product_cat-women","13":"first","14":"instock","15":"shipping-taxable","16":"purchasable","17":"product-type-variable"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Prodotto | Manzetti Clothing<\/title>\n<meta name=\"description\" content=\"Manzetti Clothing seleziona i migliori brand fashion per uomo, donna e bambino. Acquista online capi, calzature e accessori firmati!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.manzetticlothing.com\/en\/product\/women\/shoes\/sandals\/caffenero-sandali-alcantara-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prodotto | Manzetti Clothing\" \/>\n<meta property=\"og:description\" content=\"Manzetti Clothing seleziona i migliori brand fashion per uomo, donna e bambino. Acquista online capi, calzature e accessori firmati!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.manzetticlothing.com\/en\/product\/women\/shoes\/sandals\/caffenero-sandali-alcantara-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Manzetti Clothing\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T22:54:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.manzetticlothing.com\/wp-content\/uploads\/2026\/05\/PE26-caffenero-223126TMORO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1066\" \/>\n\t<meta property=\"og:image:height\" content=\"1492\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.manzetticlothing.com\/en\/product\/women\/shoes\/sandals\/caffenero-sandali-alcantara-en\/\",\"url\":\"https:\/\/www.manzetticlothing.com\/en\/product\/women\/shoes\/sandals\/caffenero-sandali-alcantara-en\/\",\"name\":\"Prodotto | Manzetti Clothing\",\"isPartOf\":{\"@id\":\"https:\/\/www.manzetticlothing.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.manzetticlothing.com\/en\/product\/women\/shoes\/sandals\/caffenero-sandali-alcantara-en\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.manzetticlothing.com\/en\/product\/women\/shoes\/sandals\/caffenero-sandali-alcantara-en\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.manzetticlothing.com\/wp-content\/uploads\/2026\/05\/PE26-caffenero-223126TMORO.jpg\",\"datePublished\":\"2026-05-12T22:54:05+00:00\",\"dateModified\":\"2026-05-12T22:54:17+00:00\",\"description\":\"Manzetti Clothing seleziona i migliori brand fashion per uomo, donna e bambino. Acquista online capi, calzature e accessori firmati!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.manzetticlothing.com\/en\/product\/women\/shoes\/sandals\/caffenero-sandali-alcantara-en\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.manzetticlothing.com\/en\/product\/women\/shoes\/sandals\/caffenero-sandali-alcantara-en\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.manzetticlothing.com\/en\/product\/women\/shoes\/sandals\/caffenero-sandali-alcantara-en\/#primaryimage\",\"url\":\"https:\/\/www.manzetticlothing.com\/wp-content\/uploads\/2026\/05\/PE26-caffenero-223126TMORO.jpg\",\"contentUrl\":\"https:\/\/www.manzetticlothing.com\/wp-content\/uploads\/2026\/05\/PE26-caffenero-223126TMORO.jpg\",\"width\":1066,\"height\":1492},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.manzetticlothing.com\/en\/product\/women\/shoes\/sandals\/caffenero-sandali-alcantara-en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.manzetticlothing.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.manzetticlothing.com\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Prodotto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.manzetticlothing.com\/en\/#website\",\"url\":\"https:\/\/www.manzetticlothing.com\/en\/\",\"name\":\"Manzetti Clothing\",\"description\":\"Vendita Abbigliamento Firmato | Shop Online Uomo Donna Bambino\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.manzetticlothing.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prodotto | Manzetti Clothing","description":"Manzetti Clothing seleziona i migliori brand fashion per uomo, donna e bambino. Acquista online capi, calzature e accessori firmati!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.manzetticlothing.com\/en\/product\/women\/shoes\/sandals\/caffenero-sandali-alcantara-en\/","og_locale":"en_US","og_type":"article","og_title":"Prodotto | Manzetti Clothing","og_description":"Manzetti Clothing seleziona i migliori brand fashion per uomo, donna e bambino. Acquista online capi, calzature e accessori firmati!","og_url":"https:\/\/www.manzetticlothing.com\/en\/product\/women\/shoes\/sandals\/caffenero-sandali-alcantara-en\/","og_site_name":"Manzetti Clothing","article_modified_time":"2026-05-12T22:54:17+00:00","og_image":[{"width":1066,"height":1492,"url":"https:\/\/www.manzetticlothing.com\/wp-content\/uploads\/2026\/05\/PE26-caffenero-223126TMORO.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.manzetticlothing.com\/en\/product\/women\/shoes\/sandals\/caffenero-sandali-alcantara-en\/","url":"https:\/\/www.manzetticlothing.com\/en\/product\/women\/shoes\/sandals\/caffenero-sandali-alcantara-en\/","name":"Prodotto | Manzetti Clothing","isPartOf":{"@id":"https:\/\/www.manzetticlothing.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.manzetticlothing.com\/en\/product\/women\/shoes\/sandals\/caffenero-sandali-alcantara-en\/#primaryimage"},"image":{"@id":"https:\/\/www.manzetticlothing.com\/en\/product\/women\/shoes\/sandals\/caffenero-sandali-alcantara-en\/#primaryimage"},"thumbnailUrl":"https:\/\/www.manzetticlothing.com\/wp-content\/uploads\/2026\/05\/PE26-caffenero-223126TMORO.jpg","datePublished":"2026-05-12T22:54:05+00:00","dateModified":"2026-05-12T22:54:17+00:00","description":"Manzetti Clothing seleziona i migliori brand fashion per uomo, donna e bambino. Acquista online capi, calzature e accessori firmati!","breadcrumb":{"@id":"https:\/\/www.manzetticlothing.com\/en\/product\/women\/shoes\/sandals\/caffenero-sandali-alcantara-en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.manzetticlothing.com\/en\/product\/women\/shoes\/sandals\/caffenero-sandali-alcantara-en\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.manzetticlothing.com\/en\/product\/women\/shoes\/sandals\/caffenero-sandali-alcantara-en\/#primaryimage","url":"https:\/\/www.manzetticlothing.com\/wp-content\/uploads\/2026\/05\/PE26-caffenero-223126TMORO.jpg","contentUrl":"https:\/\/www.manzetticlothing.com\/wp-content\/uploads\/2026\/05\/PE26-caffenero-223126TMORO.jpg","width":1066,"height":1492},{"@type":"BreadcrumbList","@id":"https:\/\/www.manzetticlothing.com\/en\/product\/women\/shoes\/sandals\/caffenero-sandali-alcantara-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.manzetticlothing.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.manzetticlothing.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Prodotto"}]},{"@type":"WebSite","@id":"https:\/\/www.manzetticlothing.com\/en\/#website","url":"https:\/\/www.manzetticlothing.com\/en\/","name":"Manzetti Clothing","description":"Vendita Abbigliamento Firmato | Shop Online Uomo Donna Bambino","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.manzetticlothing.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"df_price":56,"df_sale_price":"","df_regular_price":56,"df_image_link":"https:\/\/www.manzetticlothing.com\/wp-content\/uploads\/2026\/05\/PE26-caffenero-223126TMORO-600x840.jpg","_links":{"self":[{"href":"https:\/\/www.manzetticlothing.com\/en\/wp-json\/wp\/v2\/product\/1067979"}],"collection":[{"href":"https:\/\/www.manzetticlothing.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.manzetticlothing.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manzetticlothing.com\/en\/wp-json\/wp\/v2\/media\/1067965"}],"wp:attachment":[{"href":"https:\/\/www.manzetticlothing.com\/en\/wp-json\/wp\/v2\/media?parent=1067979"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.manzetticlothing.com\/en\/wp-json\/wp\/v2\/product_cat?post=1067979"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.manzetticlothing.com\/en\/wp-json\/wp\/v2\/product_tag?post=1067979"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.manzetticlothing.com\/en\/wp-json\/wp\/v2\/giftcard-category?post=1067979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}